{"id":1312,"date":"2010-07-20T09:27:54","date_gmt":"2010-07-20T07:27:54","guid":{"rendered":"http:\/\/www.overalia.com\/blog\/?p=1312"},"modified":"2010-07-20T09:27:54","modified_gmt":"2010-07-20T07:27:54","slug":"medicion-de-intranets-utilizando-urchin-software-de-google","status":"publish","type":"post","link":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/","title":{"rendered":"Medici\u00f3n de Intranets utilizando Urchin Software de Google"},"content":{"rendered":"<p>NOTA: Actualizaci\u00f3n del post a 30 de agosto de 2010, incluyendo una presentaci\u00f3n, sobre la importancia de medir la efectividad de las intranets y de las ventajas de hacerlo con Urchin Software, herramienta anal\u00edtica de Google.<br \/>\n<iframe style=\"border: 1px solid #CCC; border-width: 1px; margin-bottom: 5px; max-width: 100%;\" src=\"\/\/www.slideshare.net\/slideshow\/embed_code\/key\/3D7l3zj6i68D4I\" width=\"425\" height=\"355\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"> <\/iframe><\/p>\n<div style=\"margin-bottom: 5px;\"><strong> Medici\u00f3n de intranets con urchin software <\/strong> from <strong>Guillermo Vilarroig<\/strong><\/div>\n<p>Son muchas las empresas que disponen de una Intranet pero que no saben muy bien si se est\u00e1 usando o no. A veces se genera un gran esfuerzo en a\u00f1adir contenidos y aplicaciones a la intranet en aras de una mayor beneficio para toda la organizaci\u00f3n, pero no se llega a medir qu\u00e9 se utiliza y que no se est\u00e1 usando.<br \/>\nEn Overalia creemos que es imprescindible medir con detalle el uso que los empleados hacen de una intranet. Hay mucha informaci\u00f3n \u00fatil para la empresa al saber qu\u00e9 aplicaciones son m\u00e1s usadas o qu\u00e9 contenidos han sido m\u00e1s vistos por sus empleados. Y esa informaci\u00f3n debe llegar a varios estamentos de la empresa, no quedar relegada en un informe t\u00e9cnico que s\u00f3lo ver\u00e1n unos pocos. Por eso lanzamos esta propuesta: <strong>mide tu intranet con Urchin Software.<\/strong><!--more--><\/p>\n<h1>La importancia del an\u00e1lisis de la intranet<\/h1>\n<p>La Intranet es el centro de tu organizaci\u00f3n. En ella se define la cultura de la empresa. La Intranet permite\u00a0 mejorar la colaboraci\u00f3n y el aprendizaje entre tu personal y aumentar la eficiencia de los empleados.<\/p>\n<p>Las empresas que tienen el tama\u00f1o y\/o los procesos internos bien definidos suelen disponer de servicios mediante Intranets. B\u00e1sicamente los beneficios de una Intranet t\u00edpica son los siguientes:<\/p>\n<ul>\n<li>Mejorar procesos<\/li>\n<li>Incremento de eficiencia en el trabajo<\/li>\n<li>Mejorar la colaboraci\u00f3n de los empleados<\/li>\n<li>Fomentar la cultura empresarial<\/li>\n<li>Incrementar la seguridad de los datos sensibles<\/li>\n<li>Mejorar los\u00a0 procedimientos de control<\/li>\n<li>Mejorar la comunicaci\u00f3n y la interacci\u00f3n<\/li>\n<li>Proveer de informaci\u00f3n interna detallada y exacta<\/li>\n<li>Mejorar el entendimiento por parte de los empleados de las decisiones tomadas por parte de la direcci\u00f3n<\/li>\n<li>Medir y testar promociones internas<\/li>\n<\/ul>\n<p>La explotaci\u00f3n de todos estos servicios y los beneficios que puedan generar, <strong>depender\u00e1 de c\u00f3mo se haya definido la Intranet<\/strong>. Lo que est\u00e1 claro es que si funciona bien, hay un retorno evidente de la inversi\u00f3n.<\/p>\n<p>La cuesti\u00f3n es <strong>si las empresas tienen definidos unos objetivos claros, <\/strong>si saben<strong> qu\u00e9 es lo que tienen que medir <\/strong>para ver el camino a esos objetivos. Es importante determinar una serie de indicadores para <strong>valorar la eficacia de la Intranet<\/strong> y los recursos que se invierten en mantenerla.<\/p>\n<p>Estos son algunos ejemplos de contenidos y servicios que pueden medir en una intranet :<\/p>\n<ul>\n<li>Banners y destacados en la Home (promociones)<\/li>\n<li>Qui\u00e9n es qui\u00e9n en la organizaci\u00f3n (recursos humanos)<\/li>\n<li>Reserva de salas (aplicaciones)<\/li>\n<li>Gesti\u00f3n de gastos (aplicaciones)<\/li>\n<li>Acceso al fondo documental (competitividad)<\/li>\n<li>Acceso a informaci\u00f3n financiera (competitividad)<\/li>\n<li>Acceso a informaci\u00f3n confidencial (competitividad)<\/li>\n<li>Contenidos internos 2.0, blogs (recursos humanos)<\/li>\n<li>Gesti\u00f3n de incidencias (servicio atenci\u00f3n al cliente)<\/li>\n<li>En definitiva hay m\u00e1s de 140 servicios tipificados que se pueden ofrecer mediante la Intranet, e implicados muchos departamentos y perfiles distintos de usuarios<\/li>\n<\/ul>\n<p>En cualquier caso desde Overalia percibimos que se invierte mucho tiempo y dinero en crear esta infraestructura de servicios y muy poco en analizar su eficacia. Por este motivo definimos<strong> tres argumentos <\/strong>muy claros<strong> para invertir tiempo en la medici\u00f3n de la Intranet:<\/strong><\/p>\n<ol>\n<li>Has invertido ideas, tiempo y dinero. <strong>\u00bfPor qu\u00e9 no saber si funciona?<\/strong><\/li>\n<li>Muchas posibilidades de mejorar en eficacia. <strong>Tiempo es dinero\u2026 y son muchos usuarios qui\u00e9nes la usan<\/strong><\/li>\n<li>Peque\u00f1os cambios generan grandes resultados. <strong>No hace falta una gran inversi\u00f3n ni un mega proyecto<\/strong><\/li>\n<\/ol>\n<h1>Metodolog\u00eda para la medici\u00f3n de Intranets<\/h1>\n<p>El usuario final de los datos de medici\u00f3n, suele ser el equipo responsable de recursos humanos, aunque creemos que con una buena definici\u00f3n de proyecto, la informaci\u00f3n puede ser muy interesante tambi\u00e9n para otros departamentos y perfiles.<\/p>\n<p>Por este motivo os invitamos a leer este post publicado por Overalia en el Blog oficial de Google Analytics en Espa\u00f1ol, sobre la importancia de C\u00f3mo distribuir la informaci\u00f3n en la organizaci\u00f3n, mediante Google Analytics. El m\u00e9todo propuesto de distribuci\u00f3n de los informes puede ser totalmente aplicable a Urchin y a un sistema de medici\u00f3n, mediante anal\u00edtica Web, con Urchin Software.<\/p>\n<p>En todo caso, para hacer una buena medici\u00f3n de qu\u00e9 est\u00e1 pasando en tu Intranet planteamos un esquema muy sencillo:<\/p>\n<p><a href=\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/medicion_intranets-1-1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-1320\" title=\"medicion_intranets\" src=\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/medicion_intranets-1-1.jpg\" alt=\"Consultor\u00eda de medici\u00f3n de intranets\" width=\"440\" height=\"338\" \/><\/a><\/p>\n<ul>\n<li>Saber qu\u00e9 hay que medir: reflexi\u00f3n conjunta de las posibilidades de medici\u00f3n seg\u00fan la naturaleza de la Intranet (los aspectos t\u00e9cnicos condicionan la implantaci\u00f3n)<\/li>\n<li>Acompa\u00f1ar esta reflexi\u00f3n con un formaci\u00f3n sobre las posibilidades de la medici\u00f3n (aplicado al caso de la Intranet del cliente). Tambi\u00e9n hay que saber c\u00f3mo interpretar los datos.<\/li>\n<li>Definici\u00f3n de objetivos: prioridades (contenidos, usuarios, aplicaciones&#8230;) y definici\u00f3n de unos objetivos que vamos a medir. Se definen los informes e indicadores que les acompa\u00f1an.<\/li>\n<li>Configuraci\u00f3n: definici\u00f3n de c\u00f3mo tiene que ser la configuraci\u00f3n del c\u00f3digo que va en cada una de las p\u00e1ginas para poder hacer el seguimiento.<\/li>\n<li>Implantaci\u00f3n: Ajustes e implantaci\u00f3n necesarios con el equipo de IT del cliente<\/li>\n<li>An\u00e1lisis global de los informes: test de calidad de los informes y ajustes si fueran necesarios<\/li>\n<li>Si el cliente lo requiere: M\u00e1s formaci\u00f3n, seguimiento e interpretaci\u00f3n de los datos<\/li>\n<\/ul>\n<p>Y para ejecutar todo estos puntos, proponemos el uso de la herramienta <strong>Urchin<\/strong> <strong>Software<\/strong>, cuayo coste es de 2.200 \u20ac en un s\u00f3lo pago, sin actualizaciones ni cuotas a\u00f1adidas.<\/p>\n<h1>Urchin Software una soluci\u00f3n v\u00e1lida y econ\u00f3mica<\/h1>\n<p>Para qui\u00e9n no conozca Urchin Software, explicaremos que es la empresa que compr\u00f3 Google en el 2005, para convertirla meses despu\u00e9s en lo que es Google Analytics: el programa de an\u00e1lisis web, m\u00e1s utilizando en el mundo.<\/p>\n<p><a href=\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/urchin_medicion_usuario_intranet_detalle-1-1.png\"><img decoding=\"async\" class=\"alignleft size-medium wp-image-1324\" title=\"urchin_medicion_usuario_intranet_detalle\" src=\"http:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/urchin_medicion_usuario_intranet_detalle-550x389.png\" alt=\"\" width=\"550\" height=\"389\" \/><\/a><\/p>\n<p>Desde Overalia apostamos por este producto, por varias razones:<\/p>\n<ul>\n<li>Confidencialidad de los datos con urchin: los datos no salen de la empresa (como es el caso de Google Analytics, Omniture, Xiti y la mayor\u00eda de empresas que utilizan la medici\u00f3n por tags)<\/li>\n<li>Posibilidades: conociendo las posibilidades de Urchin y controlando su personalizaci\u00f3n se pueden hacer (e integrar) muchas cosas (seguimiento del comportamiento de usuarios&#8230;)<\/li>\n<li>Escalabilidad: comparado con otras soluciones, Urchin dispone de un sistema de procesamiento de la informaci\u00f3n muy r\u00e1pido y eficaz, que apenas consume recursos ni es un problema para los departamentos de IT.<\/li>\n<li>Precio: es un precio cerrado. Sin mantenimientos, ni licenciamiento por n\u00famero de p\u00e1ginas vistas. Lo pagas y te olvidas de m\u00e1s costes.<\/li>\n<li>Exportaci\u00f3n de datos con el API de Urchin: dispone de una interfaz que te permite extraer los datos en distintos formatos para que los puedas integrar con terceras aplicaciones o trabajar con excel.<\/li>\n<\/ul>\n<p>Tienes m\u00e1s informaci\u00f3n sobre Urchin Software en nuestra web de producto, Urchin Software.es o en los distintos post de nuestro blog sobre Anal\u00edtica Web. Tienes distintos art\u00edculos sobre c\u00f3mo funciona Urchin o sobre las funcionalidades de Urchin Software.<\/p>\n<p>Tambi\u00e9n tienes disponibles distintas presentaciones sobre Urchin en nuestro perfil de Slideshare de Overalia<\/p>\n<h1>Medir intranets al alcance de todas las empresas<\/h1>\n<p>Muchas empresas utilizan soluciones de medici\u00f3n cuyo coste se basa en n\u00famero de p\u00e1ginas vistas. Son herramientas muy v\u00e1lidas pero que a veces plantean dificultades en la contenci\u00f3n del presupuesto.<\/p>\n<p>Si sabes sacar todo el partido a Urchin y utilizar todo su potencial (y sobre todo a su API para extraer los datos), se pueden hacer muchas cosas y muy interesantes.<\/p>\n<p>Al margen de utilizar m\u00e9tricas a trav\u00e9s de mediciones cuantitativas (usuarios, p\u00e1ginas y secciones m\u00e1s vistas&#8230;) se puede complementar la informaci\u00f3n mediante an\u00e1lisis de audiencias, cuantificaci\u00f3n en retornos de inversi\u00f3n o an\u00e1lisis heur\u00edsticos (un grupo de expertos que analizan la interfaz y eval\u00faan cada uno de sus elementos ante una lista de principios, heur\u00edsticas, com\u00fanmente aceptadas por el sector).<\/p>\n<p>En cualquier caso, desde Overalia recomendamos empezar por lo sencillo y empezar con el m\u00e9todo aqu\u00ed propuesto. Para complicarlo siempre hay tiempo&#8230;<\/p>\n<p>Overalia es experto y uno de los escasos consultores autorizados por Google para la herramienta de medici\u00f3n web Urchin Software (tambi\u00e9n de Google Analytics y Google Web Site Optimizer) . Tambi\u00e9n es miembro de la Web Analytics Association. Ha realizado implantaciones para la medici\u00f3n de Intranets corporativas con Urchin para clientes como el grupo Eroski.<\/p>\n<p><strong>\u00bfTe interesa? Podemos estudiar tu caso y hacer una propuesta a medida<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTA: Actualizaci\u00f3n del post a 30 de agosto de 2010, incluyendo una presentaci\u00f3n, sobre la importancia de medir la efectividad de las intranets y de las ventajas de hacerlo con Urchin Software, herramienta anal\u00edtica de Google. Medici\u00f3n de intranets con urchin software from Guillermo Vilarroig Son muchas las empresas que disponen de una Intranet pero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[14,142,143,22],"class_list":["post-1312","post","type-post","status-publish","format-standard","hentry","category-university","tag-analitica-web","tag-intranets","tag-recursos-humanos","tag-urchin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Medici\u00f3n de Intranets utilizando Urchin Software de Google<\/title>\n<meta name=\"description\" content=\"En Overalia creemos que es imprescindible medir con detalle el uso que los empleados hacen de una intranet. Por eso lanzamos esta propuesta: mide tu intranet con Urchin Software. En este post te lo explicamos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medici\u00f3n de Intranets utilizando Urchin Software de Google\" \/>\n<meta property=\"og:description\" content=\"En Overalia creemos que es imprescindible medir con detalle el uso que los empleados hacen de una intranet. Por eso lanzamos esta propuesta: mide tu intranet con Urchin Software. En este post te lo explicamos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog sobre Marketing en Buscadores y Anal\u00edtica Web\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-20T07:27:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/medicion_intranets-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Overalia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Overalia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/\"},\"author\":{\"name\":\"Overalia\",\"@id\":\"https:\/\/www.overalia.com\/blog\/#\/schema\/person\/44097a8aa60295cbdf8fe39512136449\"},\"headline\":\"Medici\u00f3n de Intranets utilizando Urchin Software de Google\",\"datePublished\":\"2010-07-20T07:27:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/\"},\"wordCount\":1469,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/medicion_intranets-1-1.jpg\",\"keywords\":[\"anal\u00edtica web\",\"intranets\",\"recursos humanos\",\"urchin\"],\"articleSection\":[\"University\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/\",\"url\":\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/\",\"name\":\"Medici\u00f3n de Intranets utilizando Urchin Software de Google\",\"isPartOf\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/medicion_intranets-1-1.jpg\",\"datePublished\":\"2010-07-20T07:27:54+00:00\",\"description\":\"En Overalia creemos que es imprescindible medir con detalle el uso que los empleados hacen de una intranet. Por eso lanzamos esta propuesta: mide tu intranet con Urchin Software. En este post te lo explicamos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#primaryimage\",\"url\":\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/medicion_intranets-1-1.jpg\",\"contentUrl\":\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/medicion_intranets-1-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.overalia.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medici\u00f3n de Intranets utilizando Urchin Software de Google\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.overalia.com\/blog\/#website\",\"url\":\"https:\/\/www.overalia.com\/blog\/\",\"name\":\"Blog sobre Marketing en Buscadores y Anal\u00edtica Web\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.overalia.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.overalia.com\/blog\/#organization\",\"name\":\"Blog sobre Marketing en Buscadores y Anal\u00edtica Web\",\"url\":\"https:\/\/www.overalia.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.overalia.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2024\/07\/logo-overalia-black.svg\",\"contentUrl\":\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2024\/07\/logo-overalia-black.svg\",\"width\":416,\"height\":222,\"caption\":\"Blog sobre Marketing en Buscadores y Anal\u00edtica Web\"},\"image\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.overalia.com\/blog\/#\/schema\/person\/44097a8aa60295cbdf8fe39512136449\",\"name\":\"Overalia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.overalia.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ba0792190a366d794195b0fe8aae2e4a9da8017c875700cc271e4fed12b44f10?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ba0792190a366d794195b0fe8aae2e4a9da8017c875700cc271e4fed12b44f10?s=96&d=mm&r=g\",\"caption\":\"Overalia\"},\"sameAs\":[\"https:\/\/www.overalia.com\/blog\"],\"url\":\"https:\/\/www.overalia.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medici\u00f3n de Intranets utilizando Urchin Software de Google","description":"En Overalia creemos que es imprescindible medir con detalle el uso que los empleados hacen de una intranet. Por eso lanzamos esta propuesta: mide tu intranet con Urchin Software. En este post te lo explicamos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/","og_locale":"es_ES","og_type":"article","og_title":"Medici\u00f3n de Intranets utilizando Urchin Software de Google","og_description":"En Overalia creemos que es imprescindible medir con detalle el uso que los empleados hacen de una intranet. Por eso lanzamos esta propuesta: mide tu intranet con Urchin Software. En este post te lo explicamos.","og_url":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/","og_site_name":"Blog sobre Marketing en Buscadores y Anal\u00edtica Web","article_published_time":"2010-07-20T07:27:54+00:00","og_image":[{"width":440,"height":338,"url":"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/medicion_intranets-1.jpg","type":"image\/jpeg"}],"author":"Overalia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Overalia","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#article","isPartOf":{"@id":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/"},"author":{"name":"Overalia","@id":"https:\/\/www.overalia.com\/blog\/#\/schema\/person\/44097a8aa60295cbdf8fe39512136449"},"headline":"Medici\u00f3n de Intranets utilizando Urchin Software de Google","datePublished":"2010-07-20T07:27:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/"},"wordCount":1469,"commentCount":1,"publisher":{"@id":"https:\/\/www.overalia.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#primaryimage"},"thumbnailUrl":"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/medicion_intranets-1-1.jpg","keywords":["anal\u00edtica web","intranets","recursos humanos","urchin"],"articleSection":["University"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/","url":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/","name":"Medici\u00f3n de Intranets utilizando Urchin Software de Google","isPartOf":{"@id":"https:\/\/www.overalia.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#primaryimage"},"image":{"@id":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#primaryimage"},"thumbnailUrl":"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/medicion_intranets-1-1.jpg","datePublished":"2010-07-20T07:27:54+00:00","description":"En Overalia creemos que es imprescindible medir con detalle el uso que los empleados hacen de una intranet. Por eso lanzamos esta propuesta: mide tu intranet con Urchin Software. En este post te lo explicamos.","breadcrumb":{"@id":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#primaryimage","url":"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/medicion_intranets-1-1.jpg","contentUrl":"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2010\/07\/medicion_intranets-1-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.overalia.com\/blog\/medicion-de-intranets-utilizando-urchin-software-de-google\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.overalia.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Medici\u00f3n de Intranets utilizando Urchin Software de Google"}]},{"@type":"WebSite","@id":"https:\/\/www.overalia.com\/blog\/#website","url":"https:\/\/www.overalia.com\/blog\/","name":"Blog sobre Marketing en Buscadores y Anal\u00edtica Web","description":"","publisher":{"@id":"https:\/\/www.overalia.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.overalia.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.overalia.com\/blog\/#organization","name":"Blog sobre Marketing en Buscadores y Anal\u00edtica Web","url":"https:\/\/www.overalia.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.overalia.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2024\/07\/logo-overalia-black.svg","contentUrl":"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2024\/07\/logo-overalia-black.svg","width":416,"height":222,"caption":"Blog sobre Marketing en Buscadores y Anal\u00edtica Web"},"image":{"@id":"https:\/\/www.overalia.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.overalia.com\/blog\/#\/schema\/person\/44097a8aa60295cbdf8fe39512136449","name":"Overalia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.overalia.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ba0792190a366d794195b0fe8aae2e4a9da8017c875700cc271e4fed12b44f10?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba0792190a366d794195b0fe8aae2e4a9da8017c875700cc271e4fed12b44f10?s=96&d=mm&r=g","caption":"Overalia"},"sameAs":["https:\/\/www.overalia.com\/blog"],"url":"https:\/\/www.overalia.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/posts\/1312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/comments?post=1312"}],"version-history":[{"count":0,"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/posts\/1312\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/media?parent=1312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/categories?post=1312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/tags?post=1312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}