{"id":166,"date":"2008-11-18T10:11:00","date_gmt":"2008-11-18T08:11:00","guid":{"rendered":"http:\/\/www.overalia.com\/blog\/?p=166"},"modified":"2008-11-18T10:11:00","modified_gmt":"2008-11-18T08:11:00","slug":"estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google","status":"publish","type":"post","link":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/","title":{"rendered":"Estuvimos en el Google Analytics Authorized Consultant Summit en la sede de Google"},"content":{"rendered":"<p>Acabamos de volver de Estados Unidos, donde Guillermo Vilarroig, Luis Miguel Gonz\u00e1lez y Livia M\u00fagica han estado en la reuni\u00f3n de consultores autorizados de <a title=\"Google Analytics\" href=\"http:\/\/www.overalia.com\/analitica_web\/google_analytics\/conoce_google_analytics\/presentacion.php\">Google Analytics<\/a> que se ha celebrado en la sede de Google en Mountain View (Estados Unidos). Este tipo de reuniones son perfectas para ponerse al d\u00eda acerca de la evoluci\u00f3n de la herramienta Google Analytics y para contrastar metodolog\u00edas de trabajo con agencias de otros pa\u00edses.<\/p>\n<figure id=\"attachment_167\" aria-describedby=\"caption-attachment-167\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-167\" title=\"Livia entrando en bicicleta a la sede de Google\" src=\"http:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2009\/06\/googlesummit08_bici-300x225.jpg\" alt=\"Livia entrando en bicicleta a la sede de Google\" width=\"300\" height=\"225\" \/><figcaption id=\"caption-attachment-167\" class=\"wp-caption-text\">Livia entrando en bicicleta a la sede de Google<\/figcaption><\/figure>\n<p>Livia nos cuenta que:<\/p>\n<blockquote><p>fuimos como <a href=\"http:\/\/www.overalia.com\/analitica_web\/google_analytics\/conoce_google_analytics\/presentacion.php\"><strong>Google Analytics Authorized Consultants<\/strong><\/a> y entonces futuros <a href=\"http:\/\/www.overalia.com\/analitica_web\/google_web_site_optimizer\/conoce_google_web_site_optimizer\/presentacion.php\"><strong>Website Optimizer<\/strong><\/a> Authorized Consultants acudimos a las oficinas de Google en Montain View, California. \u00a1Unas instalaciones incre\u00edbles! Nos reunimos m\u00e1s de 200 partners de todo el mundo y personalidades como <a href=\"http:\/\/www.linkedin.com\/in\/leung\">Tom Leung<\/a>, Justin Cutroni y <a href=\"http:\/\/landingpageoptimizationbook.com\/author.html\">Tim Ash<\/a>. El summit dur\u00f3 4 d\u00edas. El primer d\u00eda se bas\u00f3 en la herramienta Google Website Optimizer. El segundo estuvo dedicado a los asuntos m\u00e1s t\u00e9cnicos de Google Analytics y como guinda del d\u00eda, la charla de <a href=\"http:\/\/es.wikipedia.org\/wiki\/Vinton_Cerf\">Vinton Cerf<\/a>, el padre de Internet.<br \/>\nEl tercer d\u00eda se focaliz\u00f3 en las novedades de la herramienta Google Analytics y el cuarto d\u00eda se dedic\u00f3 a Urchin 6 con las novedades y casos pr\u00e1cticos presentados por los partners, entre ellos, <strong>Guillermo Vilarroig de Overalia present\u00f3 un caso de estudio sobre Urchin<\/strong>, usando como referencia el trabajo que Overalia ha realizado para su cliente Permar.<\/p>\n<figure id=\"attachment_168\" aria-describedby=\"caption-attachment-168\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-medium wp-image-168\" title=\"Guillermo en la sede de Google\" src=\"http:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2009\/06\/googlesummit08_googleguillermo-300x225.jpg\" alt=\"Guillermo en la sede de Google\" width=\"300\" height=\"225\" \/><figcaption id=\"caption-attachment-168\" class=\"wp-caption-text\">Guillermo en la sede de Google<\/figcaption><\/figure><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Acabamos de volver de Estados Unidos, donde Guillermo Vilarroig, Luis Miguel Gonz\u00e1lez y Livia M\u00fagica han estado en la reuni\u00f3n de consultores autorizados de Google Analytics que se ha celebrado en la sede de Google en Mountain View (Estados Unidos). Este tipo de reuniones son perfectas para ponerse al d\u00eda acerca de la evoluci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2],"tags":[35,32,65],"class_list":["post-166","post","type-post","status-publish","format-standard","hentry","category-eventos_overalia","category-overalia","tag-consultores-google-analytics","tag-google-analytics","tag-google-analytics-summit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estuvimos en el Google Analytics Authorized Consultant Summit<\/title>\n<meta name=\"description\" content=\"Acabamos de volver de Estados Unidos, donde hemos estado en la reuni\u00f3n de consultores autorizados de\u00a0Google Analytics\u00a0que se ha celebrado en la sede de Google en Mountain View (Estados Unidos).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estuvimos en el Google Analytics Authorized Consultant Summit\" \/>\n<meta property=\"og:description\" content=\"Acabamos de volver de Estados Unidos, donde hemos estado en la reuni\u00f3n de consultores autorizados de\u00a0Google Analytics\u00a0que se ha celebrado en la sede de Google en Mountain View (Estados Unidos).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog sobre Marketing en Buscadores y Anal\u00edtica Web\" \/>\n<meta property=\"article:published_time\" content=\"2008-11-18T08:11:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2009\/06\/googlesummit08_bici-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"604\" \/>\n\t<meta property=\"og:image:height\" content=\"453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Overalia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Overalia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/\"},\"author\":{\"name\":\"Overalia\",\"@id\":\"https:\/\/www.overalia.com\/blog\/#\/schema\/person\/44097a8aa60295cbdf8fe39512136449\"},\"headline\":\"Estuvimos en el Google Analytics Authorized Consultant Summit en la sede de Google\",\"datePublished\":\"2008-11-18T08:11:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/\"},\"wordCount\":276,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2009\/06\/googlesummit08_bici-300x225.jpg\",\"keywords\":[\"consultores google analytics\",\"google analytics\",\"google analytics summit\"],\"articleSection\":[\"Eventos\",\"Overalia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/\",\"url\":\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/\",\"name\":\"Estuvimos en el Google Analytics Authorized Consultant Summit\",\"isPartOf\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2009\/06\/googlesummit08_bici-300x225.jpg\",\"datePublished\":\"2008-11-18T08:11:00+00:00\",\"description\":\"Acabamos de volver de Estados Unidos, donde hemos estado en la reuni\u00f3n de consultores autorizados de\u00a0Google Analytics\u00a0que se ha celebrado en la sede de Google en Mountain View (Estados Unidos).\",\"breadcrumb\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#primaryimage\",\"url\":\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2009\/06\/googlesummit08_bici-1.jpg\",\"contentUrl\":\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2009\/06\/googlesummit08_bici-1.jpg\",\"width\":604,\"height\":453,\"caption\":\"Livia entrando en bicicleta a la sede de Google\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.overalia.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estuvimos en el Google Analytics Authorized Consultant Summit en la sede de Google\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.overalia.com\/blog\/#website\",\"url\":\"https:\/\/www.overalia.com\/blog\/\",\"name\":\"Blog sobre Marketing en Buscadores y Anal\u00edtica Web\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.overalia.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.overalia.com\/blog\/#organization\",\"name\":\"Blog sobre Marketing en Buscadores y Anal\u00edtica Web\",\"url\":\"https:\/\/www.overalia.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.overalia.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2024\/07\/logo-overalia-black.svg\",\"contentUrl\":\"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2024\/07\/logo-overalia-black.svg\",\"width\":416,\"height\":222,\"caption\":\"Blog sobre Marketing en Buscadores y Anal\u00edtica Web\"},\"image\":{\"@id\":\"https:\/\/www.overalia.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.overalia.com\/blog\/#\/schema\/person\/44097a8aa60295cbdf8fe39512136449\",\"name\":\"Overalia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.overalia.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ba0792190a366d794195b0fe8aae2e4a9da8017c875700cc271e4fed12b44f10?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ba0792190a366d794195b0fe8aae2e4a9da8017c875700cc271e4fed12b44f10?s=96&d=mm&r=g\",\"caption\":\"Overalia\"},\"sameAs\":[\"https:\/\/www.overalia.com\/blog\"],\"url\":\"https:\/\/www.overalia.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estuvimos en el Google Analytics Authorized Consultant Summit","description":"Acabamos de volver de Estados Unidos, donde hemos estado en la reuni\u00f3n de consultores autorizados de\u00a0Google Analytics\u00a0que se ha celebrado en la sede de Google en Mountain View (Estados Unidos).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/","og_locale":"es_ES","og_type":"article","og_title":"Estuvimos en el Google Analytics Authorized Consultant Summit","og_description":"Acabamos de volver de Estados Unidos, donde hemos estado en la reuni\u00f3n de consultores autorizados de\u00a0Google Analytics\u00a0que se ha celebrado en la sede de Google en Mountain View (Estados Unidos).","og_url":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/","og_site_name":"Blog sobre Marketing en Buscadores y Anal\u00edtica Web","article_published_time":"2008-11-18T08:11:00+00:00","og_image":[{"width":604,"height":453,"url":"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2009\/06\/googlesummit08_bici-1.jpg","type":"image\/jpeg"}],"author":"Overalia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Overalia","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#article","isPartOf":{"@id":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/"},"author":{"name":"Overalia","@id":"https:\/\/www.overalia.com\/blog\/#\/schema\/person\/44097a8aa60295cbdf8fe39512136449"},"headline":"Estuvimos en el Google Analytics Authorized Consultant Summit en la sede de Google","datePublished":"2008-11-18T08:11:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/"},"wordCount":276,"commentCount":0,"publisher":{"@id":"https:\/\/www.overalia.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#primaryimage"},"thumbnailUrl":"http:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2009\/06\/googlesummit08_bici-300x225.jpg","keywords":["consultores google analytics","google analytics","google analytics summit"],"articleSection":["Eventos","Overalia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/","url":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/","name":"Estuvimos en el Google Analytics Authorized Consultant Summit","isPartOf":{"@id":"https:\/\/www.overalia.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#primaryimage"},"image":{"@id":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#primaryimage"},"thumbnailUrl":"http:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2009\/06\/googlesummit08_bici-300x225.jpg","datePublished":"2008-11-18T08:11:00+00:00","description":"Acabamos de volver de Estados Unidos, donde hemos estado en la reuni\u00f3n de consultores autorizados de\u00a0Google Analytics\u00a0que se ha celebrado en la sede de Google en Mountain View (Estados Unidos).","breadcrumb":{"@id":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#primaryimage","url":"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2009\/06\/googlesummit08_bici-1.jpg","contentUrl":"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2009\/06\/googlesummit08_bici-1.jpg","width":604,"height":453,"caption":"Livia entrando en bicicleta a la sede de Google"},{"@type":"BreadcrumbList","@id":"https:\/\/www.overalia.com\/blog\/estuvimos-en-el-google-analytics-authorized-consultant-summit-en-la-sede-de-google\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.overalia.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Estuvimos en el Google Analytics Authorized Consultant Summit en la sede de Google"}]},{"@type":"WebSite","@id":"https:\/\/www.overalia.com\/blog\/#website","url":"https:\/\/www.overalia.com\/blog\/","name":"Blog sobre Marketing en Buscadores y Anal\u00edtica Web","description":"","publisher":{"@id":"https:\/\/www.overalia.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.overalia.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.overalia.com\/blog\/#organization","name":"Blog sobre Marketing en Buscadores y Anal\u00edtica Web","url":"https:\/\/www.overalia.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.overalia.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2024\/07\/logo-overalia-black.svg","contentUrl":"https:\/\/www.overalia.com\/blog\/wp-content\/uploads\/2024\/07\/logo-overalia-black.svg","width":416,"height":222,"caption":"Blog sobre Marketing en Buscadores y Anal\u00edtica Web"},"image":{"@id":"https:\/\/www.overalia.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.overalia.com\/blog\/#\/schema\/person\/44097a8aa60295cbdf8fe39512136449","name":"Overalia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.overalia.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ba0792190a366d794195b0fe8aae2e4a9da8017c875700cc271e4fed12b44f10?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba0792190a366d794195b0fe8aae2e4a9da8017c875700cc271e4fed12b44f10?s=96&d=mm&r=g","caption":"Overalia"},"sameAs":["https:\/\/www.overalia.com\/blog"],"url":"https:\/\/www.overalia.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/posts\/166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/comments?post=166"}],"version-history":[{"count":0,"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/posts\/166\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/media?parent=166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/categories?post=166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.overalia.com\/blog\/wp-json\/wp\/v2\/tags?post=166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}